{"id":1996,"date":"2018-01-23T14:30:31","date_gmt":"2018-01-23T13:30:31","guid":{"rendered":"https:\/\/www.standard-serigraphie.com\/blog\/?p=1996"},"modified":"2018-01-23T14:52:45","modified_gmt":"2018-01-23T13:52:45","slug":"sweat-personnalise-pour-la-promo-gea-bordeaux","status":"publish","type":"post","link":"https:\/\/www.standard-serigraphie.com\/blog\/realisations\/sweat-personnalise-pour-la-promo-gea-bordeaux","title":{"rendered":"Sweat Personnalis\u00e9 pour la Promo GEA Bordeaux"},"content":{"rendered":"<p>L&rsquo;association \u00e9tudiante de la fili\u00e8re GEA de Bordeaux a choisi Standard S\u00e9rigraphie pour l&rsquo;impression de leur gamme de <a href=\"https:\/\/www.standard-serigraphie.com\/sweat.html\">Sweat de Promo Personnalis\u00e9<\/a>. Ces \u00e9tudiants pr\u00e9parant le DUT Gestion des entreprises et des administrations ont voulus mettre en avant leur promo et en faire de la publicit\u00e9.<\/p>\n<p>Cette formation pr\u00e9pare les \u00e9tudiants \u00e0 devenir des gestionnaires pour occuper des postes tels que adjoint dans une PME, charg\u00e9 de client\u00e8le, assistant RH ou encore gestionnaire de projet. Pour cela, ils vont devoir comprendre les donn\u00e9es de l\u2019environnement, de ma\u00eetriser les techniques et syst\u00e8mes de gestion et biens\u00fbr \u00e0 savoir s\u2019adapter \u00e0 un environnement\u2028 des organisations en constante \u00e9volution.<\/p>\n<p>&nbsp;<\/p>\n<h2>La promo GEA de Bordeaux a choisi notre Sweat \u00e0 capuche Personnalis\u00e9 Snake<\/h2>\n<ul>\n<li>Sweat \u00e0 capuche 50% coton Ringspun &#8211; 50% polyester<\/li>\n<li>Sweat \u00e0 capuche avec int\u00e9rieur en molleton gratt\u00e9<\/li>\n<li>Sweat \u00e0 capuche avec poignets et bas en bord c\u00f4te \u00e9lasthanne<\/li>\n<\/ul>\n<p>Le Sweat \u00e0 capuche Snake avec son style moderne est tr\u00e8s demand\u00e9 par les \u00e9coles, Universit\u00e9s, \u00e9tudiants, BDE et associations. En effet, il est l\u00e9ger tout en \u00e9tant tr\u00e8s confortable malgr\u00e9 les journ\u00e9es fraiches d&rsquo;Hiver.<\/p>\n<p><span class=\"tlf_cdefinition\">On y fait pas attention habituellement mais le molleton est un tissu de laine ou de coton gratt\u00e9 qui est un plus tr\u00e8s appr\u00e9ci\u00e9 ! Tissu chaud, doux et moelleux,\u00a0 c&rsquo;est ce qui est utilis\u00e9 pour doubler les v\u00eatements. <\/span><\/p>\n<p><span class=\"tlf_cdefinition\">C&rsquo;est en partie gr\u00e2ce \u00e0 cela, que le Sweat \u00e0 capuche Snake est favoris\u00e9, il retient vraiment la chaleur et est tr\u00e8s confortable sans \u00eatre lourd pour autant. Il est le Sweat \u00e0 capuche Personnalis\u00e9 le plus l\u00e9ger de la collection, avec seulement 280 Gr !<br \/>\n<\/span><\/p>\n<p>Sa composition ext\u00e9rieure est 50% coton et 50% polyester, ce qui permet d&rsquo;avoir un tissu confortable et \u00e0 un tr\u00e8s bon prix. Il garde le c\u00f4t\u00e9 noble du coton tout en s&rsquo;appropriant les sp\u00e9cificit\u00e9s du polyester ! Tout d&rsquo;abord, moins cher que le 100% coton, en plus il se froisse moins et se repasse facilement gr\u00e2ce aux fibres polyester.<\/p>\n<p>Les poignets et bas en \u00e9lasthanne apportent un confort suppl\u00e9mentaire ainsi qu&rsquo;une touche chic au Sweat \u00e0 capuche personnalis\u00e9.<\/p>\n<p>&nbsp;<\/p>\n<h2>Chaque Sweat a \u00e9t\u00e9 Personnalis\u00e9 en S\u00e9rigraphie<\/h2>\n<p>La s\u00e9rigraphie a \u00e9t\u00e9 choisi par les \u00e9tudiants pr\u00e9parant l&rsquo;IUT dans la fili\u00e8re GEA de Bordeaux. Cette technique est la plus utilis\u00e9e par les groupes tels que les BDE, \u00e9coles, clubs sportifs, associations&#8230;<\/p>\n<p>L&rsquo;impression des logos sur un textile via cette m\u00e9thode, est tr\u00e8s nette et propre. Cette technique tr\u00e8s traditionnelle, date de plus de 2 000 ans, a malgr\u00e9 tout su \u00e9voluer avec l&rsquo;avanc\u00e9 technologique de l&rsquo;homme. Bien entendu, l&rsquo;utilisation n&rsquo;\u00e9tait pas la m\u00eame mais elle reste tr\u00e8s similaire.<\/p>\n<p>&nbsp;<\/p>\n<h2>Sweat de Promo Personnalis\u00e9 S\u00e9rigraphi\u00e9 ou Sweat Brod\u00e9 ?<\/h2>\n<p>La broderie est la technique la plus noble dans l&rsquo;impression textile, le r\u00e9sultat sera sans conteste parfait ! Mais pour obtenir une telle impression, il faut avoir du budget&#8230;<\/p>\n<p>Lorsque vous souhaitez 25 V\u00eatements de haute qualit\u00e9, la broderie reste le 1er choix mais le Sweat Brod\u00e9 sera plus on\u00e9reux qu&rsquo;un Sweat Personnalis\u00e9 en S\u00e9rigraphie.<\/p>\n<p>C&rsquo;est alors qu&rsquo;arrive la s\u00e9rigraphie, technique tr\u00e8s r\u00e9pandue et pour cause, elle est nettement plus \u00e9conomique ! De plus l&rsquo;impression en s\u00e9rigraphie donne un rendu tr\u00e8s respectable comme vous pouvez le constater sur les r\u00e9alisations suivantes :<\/p>\n<p>&nbsp;<\/p>\n\n\t\t<style>\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 50%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-1996 gallery-columns-2 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.standard-serigraphie.com\/blog\/wp-content\/uploads\/2018\/01\/Impression-Num\u00e9rique-sur-Tee-Shirt-pour-GEA-Bordeaux-2-e1516696839688.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.standard-serigraphie.com\/blog\/wp-content\/uploads\/2018\/01\/Impression-Num\u00e9rique-sur-Tee-Shirt-pour-GEA-Bordeaux-2-e1516696839688-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-2000\" srcset=\"https:\/\/www.standard-serigraphie.com\/blog\/wp-content\/uploads\/2018\/01\/Impression-Num\u00e9rique-sur-Tee-Shirt-pour-GEA-Bordeaux-2-e1516696839688-150x150.jpg 150w, https:\/\/www.standard-serigraphie.com\/blog\/wp-content\/uploads\/2018\/01\/Impression-Num\u00e9rique-sur-Tee-Shirt-pour-GEA-Bordeaux-2-e1516696839688-440x440.jpg 440w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-2000'>\n\t\t\t\tPromo GEA Imprim\u00e9 en S\u00e9rigraphie sur Sweat \u00e0 Capuche\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.standard-serigraphie.com\/blog\/wp-content\/uploads\/2018\/01\/Impression-Num\u00e9rique-sur-Tee-Shirt-pour-GEA-Bordeaux-1-e1516696822829.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.standard-serigraphie.com\/blog\/wp-content\/uploads\/2018\/01\/Impression-Num\u00e9rique-sur-Tee-Shirt-pour-GEA-Bordeaux-1-e1516696822829-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-1999\" srcset=\"https:\/\/www.standard-serigraphie.com\/blog\/wp-content\/uploads\/2018\/01\/Impression-Num\u00e9rique-sur-Tee-Shirt-pour-GEA-Bordeaux-1-e1516696822829-150x150.jpg 150w, https:\/\/www.standard-serigraphie.com\/blog\/wp-content\/uploads\/2018\/01\/Impression-Num\u00e9rique-sur-Tee-Shirt-pour-GEA-Bordeaux-1-e1516696822829-440x440.jpg 440w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-1999'>\n\t\t\t\tSweat Personnalis\u00e9 GEA Bordeaux\n\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;association \u00e9tudiante de la fili\u00e8re GEA de Bordeaux a choisi Standard S\u00e9rigraphie pour l&rsquo;impression de leur gamme de Sweat de Promo Personnalis\u00e9. Ces \u00e9tudiants pr\u00e9parant le DUT Gestion des entreprises et des administrations ont voulus mettre en avant leur promo et en faire de la publicit\u00e9. Cette formation pr\u00e9pare les \u00e9tudiants \u00e0 devenir des gestionnaires [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1999,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[],"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[12],"tags":[16],"class_list":["post-1996","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-realisations","tag-sweats-personnalises","et-has-post-format-content","et_post_format-et-post-format-standard"],"_links":{"self":[{"href":"https:\/\/www.standard-serigraphie.com\/blog\/wp-json\/wp\/v2\/posts\/1996","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.standard-serigraphie.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.standard-serigraphie.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.standard-serigraphie.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.standard-serigraphie.com\/blog\/wp-json\/wp\/v2\/comments?post=1996"}],"version-history":[{"count":21,"href":"https:\/\/www.standard-serigraphie.com\/blog\/wp-json\/wp\/v2\/posts\/1996\/revisions"}],"predecessor-version":[{"id":2044,"href":"https:\/\/www.standard-serigraphie.com\/blog\/wp-json\/wp\/v2\/posts\/1996\/revisions\/2044"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.standard-serigraphie.com\/blog\/wp-json\/wp\/v2\/media\/1999"}],"wp:attachment":[{"href":"https:\/\/www.standard-serigraphie.com\/blog\/wp-json\/wp\/v2\/media?parent=1996"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.standard-serigraphie.com\/blog\/wp-json\/wp\/v2\/categories?post=1996"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.standard-serigraphie.com\/blog\/wp-json\/wp\/v2\/tags?post=1996"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}