{"id":1983,"date":"2018-01-23T14:11:45","date_gmt":"2018-01-23T13:11:45","guid":{"rendered":"https:\/\/www.standard-serigraphie.com\/blog\/?p=1983"},"modified":"2018-01-23T14:50:58","modified_gmt":"2018-01-23T13:50:58","slug":"tee-shirt-personnalise-en-numerique-pour-lassociation-adac-live","status":"publish","type":"post","link":"https:\/\/www.standard-serigraphie.com\/blog\/realisations\/tee-shirt-personnalise-en-numerique-pour-lassociation-adac-live","title":{"rendered":"Tee shirt Personnalis\u00e9 en Num\u00e9rique pour l&rsquo;Association ADAC Live"},"content":{"rendered":"<p>L&rsquo;ADAC est l&rsquo;<em>Association pour le D\u00e9veloppement des Arts dans le Comminges (\u00e0 la fronti\u00e8re espagnole) pr\u00e8s de Andorre. L&rsquo;association a \u00e9tait cr\u00e9\u00e9e en 1991 par deux musiciens dans le but de donner l\u2019acc\u00e8s de tous \u00e0 la Culture. C&rsquo;est un regroupement d&rsquo;\u00e9coles de musique compos\u00e9 de plus de 350 adh\u00e9rents, ils ont la possibilit\u00e9 de pratiquer n&rsquo;importe quel instrument gr\u00e2ce \u00e0 17 enseignants.<\/em><\/p>\n<p>Chaque ann\u00e9e, une dizaine de spectacles de pr\u00e8s de 2 heures sont jou\u00e9s par un Orchestre de vari\u00e9t\u00e9s compos\u00e9 d&rsquo;une cinquantaine de personnes dont 40 musiciens et 10 choristes et danseurs. C&rsquo;est l&rsquo;ADAC Live.<\/p>\n<p>L&rsquo;association a choisi Standard S\u00e9rigraphie pour l&rsquo;impression de leur logo sur<a href=\"https:\/\/www.standard-serigraphie.com\/t-shirts.html\"> Tee Shirt Personnalis\u00e9<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>L&rsquo;association ADAC Live a choisi comme Tee shirt Personnalis\u00e9 l&rsquo;Imperial 190 Gr :<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p>Ils ont s\u00e9lectionn\u00e9 notre Best Seller en <a href=\"https:\/\/www.standard-serigraphie.com\/t-shirts.html\">Tee shirt Personnalis\u00e9 pour Association<\/a> : Le Tee shirt Imp\u00e9rial pour Homme et pour Femme, d&rsquo;un grammage de 190 Gr, il est d&rsquo;une qualit\u00e9 sup\u00e9rieure au Tee shirt Regent 150 Gr (Plus \u00e9pais) et conserve malgr\u00e9 tout, un tarif tr\u00e8s comp\u00e9titif. C&rsquo;est notre Tee shirt best seller !<\/p>\n<p>Ses Caract\u00e9ristiques :<\/p>\n<ul>\n<li>Tee shirt 100% coton semi-peign\u00e9 Ringspun<\/li>\n<li>Tee shirt avec Bande de propret\u00e9 au col<\/li>\n<li>Tee shirt avec Col en \u00e9lasthanne<\/li>\n<\/ul>\n<p>Le Tee-Shirt Imp\u00e9rial Personnalis\u00e9 pour Association est le textile le plus command\u00e9 chaque ann\u00e9e ! Le col en \u00c9lasthanne offre une plus grande libert\u00e9 de mouvement, gr\u00e2ce \u00e0 sa r\u00e9sistance \u00e0 l&rsquo;allongement, c&rsquo;est un tissu qui apporte une tenue longue dur\u00e9e, confortable et r\u00e9sistant au froissage.<\/p>\n<p>Le Tee-Shirt Publicitaire Imp\u00e9rial 100% RingSpun offre un confort int\u00e9ressant avec sa surface lisse et Semi-Peign\u00e9 qui signifie que le <span id=\"ID0EYB\">fil a l&rsquo;aspect allong\u00e9 et parall\u00e8le<\/span>. Ce tissu apporte un meilleur rendu d&rsquo;impression pour votre logo. Ce large choix de 41 couleurs, vous permet de trouver la couleur qui correspond \u00e0 votre besoin. Ce qui fait de ce Tee-Shirt, le textile avec la plus grande gamme de couleurs de toute la collection textile !<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Chaque Tee shirt a \u00e9t\u00e9 Personnalis\u00e9 en Impression Num\u00e9rique DTG :<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p>Les Organisateurs de ADAC Live \u00e9tait \u00e0 la recherche d&rsquo;un Tee Shirt simple mais r\u00e9sistant. L&rsquo;impression du logo 1 Face Multi-Couleurs s&rsquo;est faite en Impression Num\u00e9rique gr\u00e2ce \u00e0 notre imprimante textile Brother GT 381 dernier cri, car, le logo \u00e9tait constitu\u00e9 de nombreux d\u00e9tails avec un panach\u00e9 de couleurs tr\u00e8s important. C&rsquo;est la technique la plus ad\u00e9quate pour des logos avec de nombreux d\u00e9tails qui offre une possibilit\u00e9 infinie de couleurs. L&rsquo;impression sera de la qualit\u00e9 du fichier envoy\u00e9 par le client (c&rsquo;est pourquoi, nous conseillons un fichier de haute qualit\u00e9) de plus, l&rsquo;impression a une tr\u00e8s longue dur\u00e9e de vie.<\/p>\n<p>&nbsp;<\/p>\n<h2>Les Avantages de l&rsquo;Impression Num\u00e9rique sur Tee shirt par rapport \u00e0 la S\u00e9rigraphie ou au Flocage :<\/h2>\n<p>&nbsp;<\/p>\n<p>Pour des marquages de visuels Quadri en petite quantit\u00e9 (Moins de 100 Tee shirts Personnalis\u00e9s) La Personnalisation en Num\u00e9rique est recommand\u00e9 face \u00e0 la s\u00e9rigraphie qui supporte des frais technique factur\u00e9 par couleurs.<\/p>\n<p>En terme de qualit\u00e9, Le Flocage est moins qualitatif que le Num\u00e9rique, en effet un tee shirt avec un logo Floqu\u00e9 aura un aspect plus plus \u00ab\u00a0plastifi\u00e9\u00a0\u00bb l&rsquo;impression d&rsquo;un tee shirt personnalis\u00e9 en Num\u00e9rique est donc aujourd&rsquo;hui le top des marquage Quadri !<\/p>\n<p>Si vous aussi vous souhaitez faire imprimer et distribuer une gamme de Tee Shirt Personnalis\u00e9 Publicitaire \u00e0 l&rsquo;effigie de votre \u00e9v\u00e8nement, de votre entreprise ou de votre association : faites appel \u00e0 notre atelier de s\u00e9rigraphie et de Flocage !<\/p>\n<p>R\u00e9ponse \u00e0 toutes vos questions ou devis sous 24 heures, demande par mail \u00e0 standard-serigraphie@orange.fr<\/p>\n<p>Galerie Photo :<\/p>\n<p>&nbsp;<\/p>\n\n\t\t<style>\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-1983 gallery-columns-3 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.standard-serigraphie.com\/blog\/wp-content\/uploads\/2018\/01\/Impression-Num\u00e9rique-sur-Tee-shirt-pour-ADAC-Live-1-e1516107121668.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.standard-serigraphie.com\/blog\/wp-content\/uploads\/2018\/01\/Impression-Num\u00e9rique-sur-Tee-shirt-pour-ADAC-Live-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-1978\" srcset=\"https:\/\/www.standard-serigraphie.com\/blog\/wp-content\/uploads\/2018\/01\/Impression-Num\u00e9rique-sur-Tee-shirt-pour-ADAC-Live-1-150x150.jpg 150w, https:\/\/www.standard-serigraphie.com\/blog\/wp-content\/uploads\/2018\/01\/Impression-Num\u00e9rique-sur-Tee-shirt-pour-ADAC-Live-1-440x440.jpg 440w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-1978'>\n\t\t\t\tBAT (Bon \u00e0 titer) des futurs Tee shirts Imprim\u00e9s\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.standard-serigraphie.com\/blog\/wp-content\/uploads\/2018\/01\/Impression-Num\u00e9rique-sur-Tee-shirt-pour-ADAC-Live-2-e1516107136379.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.standard-serigraphie.com\/blog\/wp-content\/uploads\/2018\/01\/Impression-Num\u00e9rique-sur-Tee-shirt-pour-ADAC-Live-2-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-1979\" srcset=\"https:\/\/www.standard-serigraphie.com\/blog\/wp-content\/uploads\/2018\/01\/Impression-Num\u00e9rique-sur-Tee-shirt-pour-ADAC-Live-2-150x150.jpg 150w, https:\/\/www.standard-serigraphie.com\/blog\/wp-content\/uploads\/2018\/01\/Impression-Num\u00e9rique-sur-Tee-shirt-pour-ADAC-Live-2-440x440.jpg 440w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-1979'>\n\t\t\t\tTee shirt Personnalis\u00e9 en Numerique\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.standard-serigraphie.com\/blog\/wp-content\/uploads\/2018\/01\/Impression-Num\u00e9rique-sur-Tee-shirt-pour-ADAC-Live-5-e1516552602307.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.standard-serigraphie.com\/blog\/wp-content\/uploads\/2018\/01\/Impression-Num\u00e9rique-sur-Tee-shirt-pour-ADAC-Live-5-e1516552602307-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-1982\" srcset=\"https:\/\/www.standard-serigraphie.com\/blog\/wp-content\/uploads\/2018\/01\/Impression-Num\u00e9rique-sur-Tee-shirt-pour-ADAC-Live-5-e1516552602307-150x150.jpg 150w, https:\/\/www.standard-serigraphie.com\/blog\/wp-content\/uploads\/2018\/01\/Impression-Num\u00e9rique-sur-Tee-shirt-pour-ADAC-Live-5-e1516552602307-440x440.jpg 440w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-1982'>\n\t\t\t\tZoom de l&rsquo;impression Num\u00e9rique sur Tee shirt Imp\u00e9rial\n\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.standard-serigraphie.com\/blog\/wp-content\/uploads\/2018\/01\/Impression-Num\u00e9rique-sur-Tee-shirt-pour-ADAC-Live-3-e1516107152756.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.standard-serigraphie.com\/blog\/wp-content\/uploads\/2018\/01\/Impression-Num\u00e9rique-sur-Tee-shirt-pour-ADAC-Live-3-e1516107152756-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-1980\" srcset=\"https:\/\/www.standard-serigraphie.com\/blog\/wp-content\/uploads\/2018\/01\/Impression-Num\u00e9rique-sur-Tee-shirt-pour-ADAC-Live-3-e1516107152756-150x150.jpg 150w, https:\/\/www.standard-serigraphie.com\/blog\/wp-content\/uploads\/2018\/01\/Impression-Num\u00e9rique-sur-Tee-shirt-pour-ADAC-Live-3-e1516107152756-440x440.jpg 440w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-1980'>\n\t\t\t\tLogo imprim\u00e9 en Num\u00e9rique\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.standard-serigraphie.com\/blog\/wp-content\/uploads\/2018\/01\/Impression-Num\u00e9rique-sur-Tee-shirt-pour-ADAC-Live-4-e1516107162769.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.standard-serigraphie.com\/blog\/wp-content\/uploads\/2018\/01\/Impression-Num\u00e9rique-sur-Tee-shirt-pour-ADAC-Live-4-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-1981\" srcset=\"https:\/\/www.standard-serigraphie.com\/blog\/wp-content\/uploads\/2018\/01\/Impression-Num\u00e9rique-sur-Tee-shirt-pour-ADAC-Live-4-150x150.jpg 150w, https:\/\/www.standard-serigraphie.com\/blog\/wp-content\/uploads\/2018\/01\/Impression-Num\u00e9rique-sur-Tee-shirt-pour-ADAC-Live-4-440x440.jpg 440w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-1981'>\n\t\t\t\tTee shirt personnalis\u00e9 avant d\u00e9part pour l&rsquo;associtiation ADAC\n\t\t\t\t<\/dd><\/dl>\n\t\t\t<br style='clear: both' \/>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;ADAC est l&rsquo;Association pour le D\u00e9veloppement des Arts dans le Comminges (\u00e0 la fronti\u00e8re espagnole) pr\u00e8s de Andorre. L&rsquo;association a \u00e9tait cr\u00e9\u00e9e en 1991 par deux musiciens dans le but de donner l\u2019acc\u00e8s de tous \u00e0 la Culture. C&rsquo;est un regroupement d&rsquo;\u00e9coles de musique compos\u00e9 de plus de 350 adh\u00e9rents, ils ont la possibilit\u00e9 de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1979,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[],"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[12],"tags":[39],"class_list":["post-1983","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-realisations","tag-tee-shirt-pour-association","et-has-post-format-content","et_post_format-et-post-format-standard"],"_links":{"self":[{"href":"https:\/\/www.standard-serigraphie.com\/blog\/wp-json\/wp\/v2\/posts\/1983","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.standard-serigraphie.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.standard-serigraphie.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.standard-serigraphie.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.standard-serigraphie.com\/blog\/wp-json\/wp\/v2\/comments?post=1983"}],"version-history":[{"count":12,"href":"https:\/\/www.standard-serigraphie.com\/blog\/wp-json\/wp\/v2\/posts\/1983\/revisions"}],"predecessor-version":[{"id":2049,"href":"https:\/\/www.standard-serigraphie.com\/blog\/wp-json\/wp\/v2\/posts\/1983\/revisions\/2049"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.standard-serigraphie.com\/blog\/wp-json\/wp\/v2\/media\/1979"}],"wp:attachment":[{"href":"https:\/\/www.standard-serigraphie.com\/blog\/wp-json\/wp\/v2\/media?parent=1983"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.standard-serigraphie.com\/blog\/wp-json\/wp\/v2\/categories?post=1983"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.standard-serigraphie.com\/blog\/wp-json\/wp\/v2\/tags?post=1983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}